{"id":179,"date":"2019-10-04T09:09:22","date_gmt":"2019-10-04T09:09:22","guid":{"rendered":"https:\/\/help.fooevents.com\/docs\/faqs\/account-setup\/how-do-i-setup-automatic-plugin-updates\/"},"modified":"2026-02-24T01:06:21","modified_gmt":"2026-02-24T09:06:21","slug":"wie-erstelle-ich-einen-lizenzschlussel-und-richte-automatische-plugin-updates-ein","status":"publish","type":"docs","link":"https:\/\/help.fooevents.com\/de\/docs\/frequently-asked-questions\/installation-setup\/how-do-i-create-a-license-key-and-setup-automatic-plugin-updates\/","title":{"rendered":"Wie kann ich einen FooEvents-Lizenzschl\u00fcssel erstellen und automatische Plugin-Updates einrichten?"},"content":{"rendered":"<p class=\"notice\"><strong>Bitte beachten:<\/strong> Es kann bis zu 24 Stunden dauern, bis alle \u00c4nderungen an Ihrem FooEvents-Lizenzschl\u00fcssel wirksam werden.<\/p>\n<h4><strong>Wenn Sie das Plugin von FooEvents.com erworben haben:<\/strong><\/h4>\n<div>\n<ul>\n<li>Anmelden bei <a href=\"https:\/\/www.fooevents.com\/my-account\/\" target=\"_blank\" rel=\"noopener\">Mein Konto<\/a>\u00a0auf FooEvents.com<\/li>\n<li>Klicken Sie auf die\u00a0<strong>Lizenzschl\u00fcssel<\/strong> Registerkarte<\/li>\n<li><strong>Geben Sie Ihre Website-URL ein<\/strong> (<strong>NB:<\/strong> Vergewissern Sie sich, dass Sie den Namen genau so eingeben, wie er in Ihrem Webbrowser erscheint (http:\/\/ ODER https:\/\/). <strong>Tipp:<\/strong> Wir empfehlen, die URL direkt aus der Adressleiste Ihres Webbrowsers zu kopieren und einzuf\u00fcgen, um Fehler zu vermeiden<\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-146570 size-full alignnone\" style=\"font-style: inherit; font-weight: 600;\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/Image-2026-02-24-at-4.47.18-PM.png\" alt=\"Screenshot einer FooEvents-Kontoseite mit der Registerkarte Lizenzschl\u00fcssel, auf der Sie die URL der Website eingeben k\u00f6nnen\" width=\"1421\" height=\"624\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/Image-2026-02-24-at-4.47.18-PM.png 1421w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/Image-2026-02-24-at-4.47.18-PM-300x132.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/Image-2026-02-24-at-4.47.18-PM-1024x450.png 1024w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/Image-2026-02-24-at-4.47.18-PM-768x337.png 768w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/Image-2026-02-24-at-4.47.18-PM-18x8.png 18w\" sizes=\"(max-width: 1421px) 100vw, 1421px\" \/><\/p>\n<ul>\n<li>Klicken Sie auf die Schaltfl\u00e4che '<strong>\u00c4nderungen speichern<\/strong>\" Schaltfl\u00e4che<\/li>\n<li>Kopieren Sie Ihr einzigartiges <strong>FooEvents-Lizenzschl\u00fcssel<\/strong><\/li>\n<li>Navigieren Sie zu <strong>FooEvents<\/strong><em> &gt; <\/em><strong>Einstellungen<\/strong><em> &gt; <\/em><strong>Lizenz<\/strong> aus dem Seitenleistenmen\u00fc in Ihrem WordPress-Administrations-Dashboard<\/li>\n<li>F\u00fcgen Sie Ihren Lizenzschl\u00fcssel in das Feld \"<strong>FooEvents-Lizenzschl\u00fcssel<\/strong>\"Feld und klicken Sie auf \"<strong>\u00c4nderungen speichern<\/strong>\"<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-2462 size-full\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/12\/FooEvents-Settings-license-Key-e1585744697282.png\" alt=\"\" width=\"895\" height=\"299\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/12\/FooEvents-Settings-license-Key-e1585744697282.png 895w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/12\/FooEvents-Settings-license-Key-e1585744697282-300x100.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/12\/FooEvents-Settings-license-Key-e1585744697282-768x257.png 768w\" sizes=\"(max-width: 895px) 100vw, 895px\" \/><\/p>\n<p><strong>FooEvents POS <\/strong>Kunden m\u00fcssen auch \u00fcberpr\u00fcfen, ob Ihre Lizenz korrekt in <strong>FooEvents POS<\/strong> &gt; <strong>Einstellungen<\/strong> &gt; <strong>Allgemein<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-133680\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents_License_Key_POS_General_Settings.png\" alt=\"\" width=\"895\" height=\"115\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents_License_Key_POS_General_Settings.png 1262w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents_License_Key_POS_General_Settings-300x39.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents_License_Key_POS_General_Settings-1024x131.png 1024w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents_License_Key_POS_General_Settings-768x99.png 768w\" sizes=\"(max-width: 895px) 100vw, 895px\" \/><\/p>\n<\/div>\n<h4><strong>Wenn Sie das Plugin von CodeCanyon erworben haben:<\/strong><\/h4>\n<div>\n<ul>\n<li>Navigieren Sie zu <strong>FooEvents<\/strong><i> &gt; <\/i><strong>Einstellungen<\/strong><i> &gt; <\/i><strong>Lizenz<\/strong> aus dem Seitenleistenmen\u00fc in Ihrem WordPress-Administrations-Dashboard<\/li>\n<li>F\u00fcgen Sie Ihren Code in das Feld \"<strong>Envato Einkaufscode<\/strong>\"Feld und klicken Sie auf \"<strong>\u00c4nderungen speichern<\/strong>\"<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2464\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents-Settings-envato-1-e1585744829188.png\" alt=\"\" width=\"895\" height=\"305\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents-Settings-envato-1-e1585744829188.png 897w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents-Settings-envato-1-e1585744829188-300x102.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents-Settings-envato-1-e1585744829188-768x262.png 768w\" sizes=\"(max-width: 895px) 100vw, 895px\" \/><\/p>\n<h4><strong>Wenn Sie Plugins von FooEvents.com UND CodeCanyon gekauft haben:<\/strong><\/h4>\n<ul>\n<li>F\u00fchren Sie die oben beschriebenen Schritte zur Erstellung Ihrer <strong>FooEvents-Lizenzschl\u00fcssel <\/strong>und die Erlangung Ihrer <strong>Envato Einkaufscode<\/strong><\/li>\n<li>Navigieren Sie zu <strong>FooEvents<\/strong><i> &gt; <\/i><strong>Einstellungen<\/strong><i> &gt; <\/i><strong>Lizenz<\/strong> aus dem Seitenleistenmen\u00fc in Ihrem WordPress-Administrations-Dashboard<\/li>\n<li>F\u00fcgen Sie Ihren FooEvents-Lizenzschl\u00fcssel in das Feld \"<strong>FooEvents-Lizenzschl\u00fcssel<\/strong>\"Kasten <strong>UND<\/strong> Ihren Envato-Code in das Feld \"<strong>Envato Einkaufscode<\/strong>\"Feld und klicken Sie auf \"<strong>\u00c4nderungen speichern<\/strong>\"<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2465\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents-Settings-both-1-e1585744848556.png\" alt=\"\" width=\"895\" height=\"305\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents-Settings-both-1-e1585744848556.png 897w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents-Settings-both-1-e1585744848556-300x102.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2019\/10\/FooEvents-Settings-both-1-e1585744848556-768x262.png 768w\" sizes=\"(max-width: 895px) 100vw, 895px\" \/><\/p>\n<\/div>","protected":false},"featured_media":0,"parent":162,"menu_order":2,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"doc_tag":[66,70,69,126,68,125,497,18,660],"class_list":["post-179","docs","type-docs","status-publish","hentry","doc_tag-automatic-updates","doc_tag-codecanyon","doc_tag-envato","doc_tag-envato-purchase-code","doc_tag-expired","doc_tag-fooevents-license-key","doc_tag-fooevents-pos","doc_tag-license-key","doc_tag-subdomain"],"comment_count":0,"_links":{"self":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/types\/docs"}],"replies":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":3,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/179\/revisions"}],"predecessor-version":[{"id":146573,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/179\/revisions\/146573"}],"up":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/162"}],"next":[{"title":"Kann ich FooEvents auf einer Staging-Site installieren, bevor ich es in eine Produktionsumgebung \u00fcbertrage?","link":"https:\/\/help.fooevents.com\/de\/docs\/frequently-asked-questions\/installation-setup\/can-i-install-fooevents-on-a-staging-site\/","href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/186"}],"prev":[{"title":"Kann ich FooEvents in einem WordPress Multisite- oder Multivendor-Netzwerk installieren?","link":"https:\/\/help.fooevents.com\/de\/docs\/frequently-asked-questions\/installation-setup\/can-i-install-fooevents-on-a-multisite-multi-vendor-network\/","href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/502"}],"wp:attachment":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/media?parent=179"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/doc_tag?post=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}