{"id":877,"date":"2019-11-27T07:14:58","date_gmt":"2019-11-27T14:14:58","guid":{"rendered":"https:\/\/help.fooevents.com\/docs\/topics\/tickets\/delete-tickets\/"},"modified":"2026-06-03T06:21:52","modified_gmt":"2026-06-03T13:21:52","slug":"tickets-loschen","status":"publish","type":"docs","link":"https:\/\/help.fooevents.com\/de\/docs\/topics\/tickets\/delete-tickets\/","title":{"rendered":"Tickets l\u00f6schen"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Wenn Sie eine Anfrage bearbeiten, k\u00f6nnen Sie die Anfrage mit der Schaltfl\u00e4che <strong>In den Papierkorb verschieben<\/strong> Option in den Ver\u00f6ffentlichungseinstellungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alternativ k\u00f6nnen Sie Tickets auch in gro\u00dfen Mengen l\u00f6schen, indem Sie die folgenden Schritte ausf\u00fchren:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Gehe zu\u00a0<strong>FooEvents<\/strong>\u00a0>\u00a0<strong>Eintrittskarten<\/strong>\u00a0im Hauptmen\u00fc<\/li>\n\n\n\n<li>W\u00e4hlen Sie alle <strong>Eintrittskarten<\/strong> die Sie l\u00f6schen m\u00f6chten<\/li>\n\n\n\n<li>Klicken Sie auf\u00a0<strong>Bulk-Aktionen<\/strong> >\u00a0<strong>In den Papierkorb verschieben<\/strong> >\u00a0<strong>Bewerbung<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie Schwierigkeiten haben, Tickets in gro\u00dfen Mengen zu l\u00f6schen, versuchen Sie bitte Folgendes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Gehe zu\u00a0<strong>FooEvents<\/strong>\u00a0>\u00a0<strong>Eintrittskarten<\/strong>\u00a0im Hauptmen\u00fc<\/li>\n\n\n\n<li>W\u00e4hlen Sie alle <strong>Eintrittskarten<\/strong> die Sie l\u00f6schen m\u00f6chten<\/li>\n\n\n\n<li>Klicken Sie auf\u00a0<strong>Bulk-Aktionen<\/strong> >\u00a0<strong>bearbeiten<\/strong> >\u00a0<strong>Bewerbung<\/strong><\/li>\n\n\n\n<li>Setzen Sie den Status auf\u00a0<strong>Entwurf<\/strong>\u00a0und\u00a0<strong>Update<\/strong><\/li>\n\n\n\n<li>W\u00e4hlen Sie sie erneut aus und verschieben Sie sie in den Papierkorb.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">L\u00f6schung eines Auftrags<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Durch das L\u00f6schen einer Bestellung werden die Tickets, die f\u00fcr den Kunden erstellt wurden, nicht automatisch gel\u00f6scht und deaktiviert. Das hei\u00dft, selbst wenn die Bestellung erstattet oder gel\u00f6scht wurde, kann der Kunde das Ticket weiterhin nutzen, z. B. beim Scannen des Ticket-Barcodes mit der Funktion <strong>FooEvents Check-ins App<\/strong> wird das Ticket weiterhin als g\u00fcltig angezeigt. Sie m\u00fcssen die Bestellung erstatten und dann <strong>delete&nbsp;the ticket<\/strong>&nbsp;und&nbsp;<strong>die Bestandsnummer manuell aktualisieren<\/strong>&nbsp;wenn Sie dies \u00fcber WooCommerce verwalten. Dies entspricht der Standardfunktionalit\u00e4t von WooCommerce, bei der Sie jemandem eine R\u00fcckerstattung gew\u00e4hren, ihm aber dennoch erlauben, den Bestand zu behalten\/zu nutzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abbrechen<\/strong> wird der Status des Tickets jedoch auf \"Storniert\" gesetzt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier finden Sie weitere Informationen: <a href=\"https:\/\/help.fooevents.com\/de\/dokumentation\/faq\/eintrittskarten\/sind-tickets-noch-gultig-wenn-die-bestellung-geloscht-wurde\/\">https:\/\/help.fooevents.com\/docs\/frequently-asked-questions\/tickets\/are-tickets-still-valid-if-the-order-was-deleted\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>When editing a ticket, you can delete the ticket using the Move to trash option in the publish settings. Alternatively you can delete tickets in bulk following these steps: If you are experience difficulty deleting tickets in bulk, please try the following: Deleting an order Deleting an order does not automatically delete and deactivate the [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":942,"menu_order":5,"template":"","doc_tag":[175,177,183,159,108,7],"class_list":["post-877","docs","type-docs","status-publish","hentry","doc_tag-delete","doc_tag-inventory","doc_tag-manage-stock","doc_tag-refund","doc_tag-stock","doc_tag-tickets"],"_links":{"self":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/types\/docs"}],"version-history":[{"count":2,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/877\/revisions"}],"predecessor-version":[{"id":148654,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/877\/revisions\/148654"}],"up":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/942"}],"wp:attachment":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/media?parent=877"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/doc_tag?post=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}