{"id":961,"date":"2019-11-27T07:12:20","date_gmt":"2019-11-27T14:12:20","guid":{"rendered":"https:\/\/help.fooevents.com\/docs\/topics\/installation-setup\/installing-wordpress\/"},"modified":"2019-11-27T07:12:20","modified_gmt":"2019-11-27T14:12:20","slug":"wordpress-installieren","status":"publish","type":"docs","link":"https:\/\/help.fooevents.com\/de\/docs\/topics\/installation\/installing-wordpress\/","title":{"rendered":"Installation von WordPress"},"content":{"rendered":"<h3>Was ist WordPress?<\/h3>\n<p>WordPress ist eine Open-Source-Software, mit der Sie eine sch\u00f6ne Website, einen Blog oder eine App erstellen k\u00f6nnen. WordPress ist eine vertrauensw\u00fcrdige L\u00f6sung und betreibt 28% der Websites weltweit, von Hobby-Blogs bis hin zu den gr\u00f6\u00dften Nachrichtenseiten im Internet. Erweitern Sie WordPress mit \u00fcber 45.000 Plugins, damit Ihre Website Ihren Anforderungen entspricht. F\u00fcgen Sie einen Online-Shop, Galerien, Mailinglisten, Foren, Analysefunktionen und\u00a0<a href=\"https:\/\/wordpress.org\/plugins\/\" target=\"_blank\" rel=\"noopener\">viel mehr<\/a>.<\/p>\n<h3>Muss ich WordPress verwenden?<\/h3>\n<p>Ja! FooEvents ist eine WordPress-Erweiterung und erg\u00e4nzt WordPress um Event- und Ticketing-Funktionen.<\/p>\n<h3>WordPress Installationsanleitung<\/h3>\n<p>Wenn Sie noch nicht \u00fcber eine funktionierende WordPress-Installation verf\u00fcgen, m\u00fcssen Sie zun\u00e4chst WordPress auf Ihrem Webserver installieren:\u00a0<a href=\"https:\/\/codex.wordpress.org\/Installing_WordPress\" target=\"\" rel=\"noopener noreferrer nofollow\">https:\/\/codex.wordpress.org\/Installing_WordPress<\/a><\/p>\n<h3>Was brauche ich sonst noch?<\/h3>\n<p>Au\u00dferdem m\u00fcssen Sie\u00a0<a href=\"https:\/\/help.fooevents.com\/de\/dokumentation\/themen\/installations-setup\/installation-von-woocommerce\/\">WooCommerce installieren<\/a>\u00a0das ein f\u00fcr WordPress entwickeltes E-Commerce-System ist. Sie k\u00f6nnen mehr \u00fcber es herausfinden\u00a0<a href=\"https:\/\/help.fooevents.com\/de\/dokumentation\/themen\/installations-setup\/installation-von-woocommerce\/\">hier<\/a>.<\/p>","protected":false},"featured_media":0,"parent":939,"menu_order":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"doc_tag":[],"class_list":["post-961","docs","type-docs","status-publish","hentry"],"comment_count":0,"_links":{"self":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/types\/docs"}],"replies":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/comments?post=961"}],"version-history":[{"count":0,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/961\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/939"}],"next":[{"title":"Installation von WooCommerce","link":"https:\/\/help.fooevents.com\/de\/docs\/topics\/installation\/installing-woocommerce\/","href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/962"}],"prev":[{"title":"Mindestanforderungen","link":"https:\/\/help.fooevents.com\/de\/docs\/topics\/installation\/minimum-requirements\/","href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/docs\/960"}],"wp:attachment":[{"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/media?parent=961"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/help.fooevents.com\/de\/wp-json\/wp\/v2\/doc_tag?post=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}