{"id":1340,"date":"2019-12-11T08:20:10","date_gmt":"2019-12-11T15:20:10","guid":{"rendered":"https:\/\/help.fooevents.com\/?post_type=docs&#038;p=1340"},"modified":"2026-06-03T05:56:21","modified_gmt":"2026-06-03T12:56:21","slug":"escaneo-de-billetes-con-la-aplicacion","status":"publish","type":"docs","link":"https:\/\/help.fooevents.com\/es\/docs\/topics\/check-ins-app\/ticket-scanning-with-the-app\/","title":{"rendered":"Escanear billetes con la aplicaci\u00f3n"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La aplicaci\u00f3n FooEvents Check-ins utiliza la c\u00e1mara integrada del dispositivo m\u00f3vil y las bibliotecas del sistema operativo para escanear los c\u00f3digos de barras de los billetes. La precisi\u00f3n y la velocidad de escaneado dependen en gran medida de la calidad y la capacidad del dispositivo, no de la aplicaci\u00f3n. En general, hemos comprobado que los smartphones de gama alta, en particular los \u00faltimos iPhone, son los que mejor funcionan, ya que suelen incorporar la \u00faltima tecnolog\u00eda en c\u00e1maras y el procesador m\u00e1s r\u00e1pido del mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n puede conectar un esc\u00e1ner de c\u00f3digos de barras Bluetooth port\u00e1til a la aplicaci\u00f3n FooEvents Check-ins para obtener la m\u00e1xima precisi\u00f3n y velocidad de escaneado. Le recomendamos que lo haga si tiene problemas para escanear c\u00f3digos de barras con la c\u00e1mara integrada de su dispositivo m\u00f3vil o si va a escanear c\u00f3digos de barras en un entorno con poca luz.<\/p>\n\n\n\n<p class=\"notice wp-block-paragraph\">Leer el <a href=\"https:\/\/help.fooevents.com\/es\/documentos\/temas-2\/entradas-2\/escanear-billetes\/#scanning-using-the-event-check-ins-apps\">Escaneado de billetes<\/a>&nbsp;doc para obtener instrucciones m\u00e1s detalladas<\/p>","protected":false},"excerpt":{"rendered":"<p>The FooEvents Check-ins app uses the mobile device\u2019s built-in camera and operating system libraries to scan ticket barcodes. The accuracy and speed of scanning is very much dependent on the quality and capability of the device, not the app. In general, we have found that higher end smartphones, particularly the latest iPhone, performs best as [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":944,"menu_order":2,"template":"","doc_tag":[187,22,148,12,196,276],"class_list":["post-1340","docs","type-docs","status-publish","hentry","doc_tag-barcodes","doc_tag-bluetooth","doc_tag-camera","doc_tag-check-ins","doc_tag-fooevents-check-ins","doc_tag-scanning"],"_links":{"self":[{"href":"https:\/\/help.fooevents.com\/es\/wp-json\/wp\/v2\/docs\/1340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.fooevents.com\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/help.fooevents.com\/es\/wp-json\/wp\/v2\/types\/docs"}],"version-history":[{"count":1,"href":"https:\/\/help.fooevents.com\/es\/wp-json\/wp\/v2\/docs\/1340\/revisions"}],"predecessor-version":[{"id":148531,"href":"https:\/\/help.fooevents.com\/es\/wp-json\/wp\/v2\/docs\/1340\/revisions\/148531"}],"up":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/es\/wp-json\/wp\/v2\/docs\/944"}],"wp:attachment":[{"href":"https:\/\/help.fooevents.com\/es\/wp-json\/wp\/v2\/media?parent=1340"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/help.fooevents.com\/es\/wp-json\/wp\/v2\/doc_tag?post=1340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}