{"id":185,"date":"2019-10-04T09:10:02","date_gmt":"2019-10-04T09:10:02","guid":{"rendered":"https:\/\/help.fooevents.com\/docs\/faqs\/check-in-apps\/the-app-seems-to-stop-working-after-a-while-what-should-i-do\/"},"modified":"2026-06-03T06:29:12","modified_gmt":"2026-06-03T13:29:12","slug":"lapp-smette-di-funzionare","status":"publish","type":"docs","link":"https:\/\/help.fooevents.com\/it\/docs\/frequently-asked-questions\/check-ins-app\/the-app-stops-working\/","title":{"rendered":"Perch\u00e9 l'app FooEvents Check-in smette di funzionare dopo un po'?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">L'applicazione FooEvents Check-in si connette al sito web WordPress tramite l'applicazione <strong>API REST<\/strong>. Vi consigliamo di verificare che il vostro sito web sia <strong>API REST<\/strong> \u00e8 accessibile digitando il seguente indirizzo nel browser web: 'www.YOURWEBSITE.com\/wp-json\/fooevents\/v1'. Dovrebbe apparire una schermata che visualizza il codice che inizia con <code style=\"background-color: #FFF2E0;\">{\"namespace\": \"fooevents\\\/v1\", \"routes\":<\/code> rispetto a una pagina di errore come <em>404 file non trovato<\/em> che indica che c'\u00e8 qualcosa che non va nella configurazione del server o nel file <strong>API REST<\/strong> \u00e8 bloccato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se il <strong>API REST<\/strong> non \u00e8 accessibile e l'applicazione tenta di ripiegare sul meno preferito <strong>XML-RPC<\/strong> verificare che la connessione sia <strong>Il file xmlrpc.php \u00e8 accessibile<\/strong>. Digitare \"www.YOURSITE.com\/xmlrpc.php\" nel browser web. Se il file xmlrpc.php \u00e8 accessibile, dovrebbe apparire il seguente messaggio: \"Il server XML-RPC accetta solo richieste POST\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">FooEvents utilizza il <strong>XML-RPC<\/strong> per lo scopo previsto, tuttavia gli spammer spesso utilizzano questo file per scopi nefasti. Per questo motivo, alcuni provider di hosting o plugin di sicurezza possono segnalare erroneamente l'aumento delle richieste al server attraverso questo file come sospetto e bloccare l'accesso dell'applicazione FooEvents Check-ins al server. <strong>XML-RPC<\/strong> file.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se sul vostro sito web \u00e8 installato un plugin di sicurezza, come Wordfence, disattivatelo temporaneamente e provate ad accedere nuovamente all'applicazione. Se si riesce ad accedere, il plugin bloccava l'accesso e deve essere disattivato in modo permanente o configurato diversamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Potete anche chiedere alla vostra societ\u00e0 di hosting di assicurarsi che non ci siano restrizioni di sicurezza sul file \"xmlrpc.php\" che fa parte dell'WordPress e di inserire nella whitelist tutti gli indirizzi IP del vostro server per la durata dell'evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, vi consigliamo vivamente di testare l'applicazione il pi\u00f9 possibile prima dell'evento e, per sicurezza, assicuratevi di disporre di un piano di emergenza, ad esempio un foglio di calcolo contenente tutti i partecipanti all'evento.<\/p>","protected":false},"excerpt":{"rendered":"<p>The FooEvents Check-ins app connects to your WordPress website via the REST API. We recommend that you confirm that your website&#8217;s REST API is accessible by entering the following address in your web browser: &#8216;www.YOURWEBSITE.com\/wp-json\/fooevents\/v1&#8217;. You should see a screen that displays code which starts with {&#8220;namespace&#8221;:&#8221;fooevents\\\/v1&#8243;,&#8221;routes&#8221;: as opposed to an error page such as [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":161,"menu_order":5,"template":"","doc_tag":[13,12,14,196,17,15,16,10,11],"class_list":["post-185","docs","type-docs","status-publish","hentry","doc_tag-app","doc_tag-check-ins","doc_tag-connection","doc_tag-fooevents-check-ins","doc_tag-login","doc_tag-sign-in","doc_tag-wordfence","doc_tag-xml-rpc","doc_tag-xmlrpc"],"_links":{"self":[{"href":"https:\/\/help.fooevents.com\/it\/wp-json\/wp\/v2\/docs\/185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.fooevents.com\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/help.fooevents.com\/it\/wp-json\/wp\/v2\/types\/docs"}],"version-history":[{"count":1,"href":"https:\/\/help.fooevents.com\/it\/wp-json\/wp\/v2\/docs\/185\/revisions"}],"predecessor-version":[{"id":148708,"href":"https:\/\/help.fooevents.com\/it\/wp-json\/wp\/v2\/docs\/185\/revisions\/148708"}],"up":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/it\/wp-json\/wp\/v2\/docs\/161"}],"wp:attachment":[{"href":"https:\/\/help.fooevents.com\/it\/wp-json\/wp\/v2\/media?parent=185"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/help.fooevents.com\/it\/wp-json\/wp\/v2\/doc_tag?post=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}