{"id":957,"date":"2019-11-27T07:11:38","date_gmt":"2019-11-27T14:11:38","guid":{"rendered":"https:\/\/help.fooevents.com\/docs\/topics\/products\/fooevents-seating\/"},"modified":"2026-06-03T06:15:10","modified_gmt":"2026-06-03T13:15:10","slug":"fooevents-zitplaatsen","status":"publish","type":"docs","link":"https:\/\/help.fooevents.com\/nl\/docs\/topics\/fooevents-plugins\/fooevents-seating\/","title":{"rendered":"FooEvents Stoel"},"content":{"rendered":"<p class=\"notice wp-block-paragraph\">Bezoek de plugin <a href=\"https:\/\/www.fooevents.com\/products\/fooevents-seating\/\" target=\"_blank\" rel=\"noopener\">product informatie pagina<\/a> of koop het als onderdeel van een <a href=\"https:\/\/www.fooevents.com\/pricing\/\" target=\"_blank\" rel=\"noopener\">bundel<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De FooEvents Seating plugin is een uitbreiding voor FooEvents waarmee je gasten of aanwezigen hun zitplaatsen kunnen kiezen bij het afrekenen op basis van de lay-out van je locatie. Deze plugin kan worden gebruikt om rijen en stoelen in een vergaderzaal of theater, tafels en het aantal stoelen aan de tafel, enz. Je kunt VIP-gedeeltes maken of bezoekers beperken tot zitplaatsen in andere hoger of lager geprijsde gedeeltes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Help-onderwerpen<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/help.fooevents.com\/nl\/documentatie\/onderwerpen\/installatie-instelling\/fooevents-plugins-installeren\/\">Plugin installeren<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/help.fooevents.com\/nl\/documentatie\/onderwerpen\/evenementen\/tafelkaarten\/\">Opstelling tafelschikking<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/help.fooevents.com\/nl\/documentatie\/onderwerpen\/evenementen\/tafelkaarten\/#link-rows-to-variations\">Rijen koppelen aan variaties<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/help.fooevents.com\/nl\/documentatie\/onderwerpen\/evenementen\/tafelkaarten\/#visual-seating-chart\">Visuele tafelschikking<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/help.fooevents.com\/nl\/documentatie\/onderwerpen\/evenementen\/tafelkaarten\/#changing-seating-chart-colors\">Kleuren tafelschikking wijzigen<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/help.fooevents.com\/nl\/documentatie\/onderwerpen\/evenementen\/tafelkaarten\/#modifying-seats\">Stoelen aanpassen<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Visit the plugin product information page or purchase it as part of a bundle The FooEvents Seating plugin is an extension for FooEvents that allows your guests or attendees to select their seats at checkout based on the layout of your venue. This plugin can be used to specify rows and seats in a conference [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":938,"menu_order":4,"template":"","doc_tag":[],"class_list":["post-957","docs","type-docs","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/help.fooevents.com\/nl\/wp-json\/wp\/v2\/docs\/957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.fooevents.com\/nl\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/help.fooevents.com\/nl\/wp-json\/wp\/v2\/types\/docs"}],"version-history":[{"count":1,"href":"https:\/\/help.fooevents.com\/nl\/wp-json\/wp\/v2\/docs\/957\/revisions"}],"predecessor-version":[{"id":148619,"href":"https:\/\/help.fooevents.com\/nl\/wp-json\/wp\/v2\/docs\/957\/revisions\/148619"}],"up":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/nl\/wp-json\/wp\/v2\/docs\/938"}],"wp:attachment":[{"href":"https:\/\/help.fooevents.com\/nl\/wp-json\/wp\/v2\/media?parent=957"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/help.fooevents.com\/nl\/wp-json\/wp\/v2\/doc_tag?post=957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}