{"id":133388,"date":"2022-07-13T05:08:55","date_gmt":"2022-07-13T11:08:55","guid":{"rendered":"https:\/\/help.fooevents.com\/docs\/topics\/use-cases\/bookable-party-venue-booking\/"},"modified":"2026-06-03T06:22:48","modified_gmt":"2026-06-03T13:22:48","slug":"reserva-de-local-de-festa-reservavel","status":"publish","type":"docs","link":"https:\/\/help.fooevents.com\/pt\/docs\/topics\/use-cases\/bookable-party-venue-booking\/","title":{"rendered":"Pode ser reservado: Reserva de local para festas"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Cen\u00e1rio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uma empresa de organiza\u00e7\u00e3o de festas gostaria de permitir que os clientes efectuassem reservas no local atrav\u00e9s do seu s\u00edtio Web. O local pode ser reservado em dias espec\u00edficos e em duas faixas hor\u00e1rias diferentes. A empresa tamb\u00e9m oferece servi\u00e7os adicionais, tais como pacotes de festas, entretenimento e aluguer de equipamento, que s\u00e3o oferecidos como vendas adicionais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando um cliente compra um bilhete, deve ocorrer o seguinte:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O comprador deve selecionar a data e a hora pretendidas para a reserva<\/li>\n\n\n\n<li>O comprador deve especificar se pretende pacotes de festa, anima\u00e7\u00e3o ou aluguer de equipamento adicional<\/li>\n\n\n\n<li>No momento da compra, o comprador deve introduzir os seus dados de contacto, as suas necessidades alimentares e o tema da festa<\/li>\n\n\n\n<li>O bilhete\/e-mail de confirma\u00e7\u00e3o deve ser enviado ao comprador<\/li>\n<\/ul>\n\n\n\n<p class=\"notice wp-block-paragraph\">Eis um exemplo de um evento deste g\u00e9nero: <a href=\"https:\/\/demo.fooevents.com\/product\/party-venue-booking\/\" rel=\"nofollow noopener\" target=\"_blank\">Reserva de local para festas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Este documento de ajuda pressup\u00f5e que o utilizador j\u00e1 tem&nbsp;<a href=\"http:\/\/fooevents.com\/\" target=\"_blank\" rel=\"noopener\">FooEvents<\/a>&nbsp;e&nbsp;<a href=\"https:\/\/help.fooevents.com\/pt\/documentos\/temas-2\/configuracao-da-instalacao\/instalar-o-woocommerce\/\">WooCommerce<\/a>&nbsp;instalado num&nbsp;<a href=\"https:\/\/help.fooevents.com\/pt\/documentos\/temas-2\/configuracao-da-instalacao\/instalar-o-wordpress\/\">WordPress<\/a>&nbsp;e ter uma compreens\u00e3o b\u00e1sica de como funciona o FooEvents. Se \u00e9 novo no FooEvents, deve ler o nosso&nbsp;<a href=\"https:\/\/help.fooevents.com\/pt\/documentos\/temas-2\/comecar\/\">Come\u00e7ar a trabalhar<\/a>&nbsp;guia para o ajudar a come\u00e7ar.&nbsp;<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Produtos utilizados<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.fooevents.com\/fooevents-for-woocommerce\/\" target=\"_blank\" rel=\"noopener\">FooEvents para WooCommerce<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.fooevents.com\/fooevents-bookings\/\" target=\"_blank\" rel=\"noopener\">FooEvents Plugin de reservas<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.fooevents.com\/products\/fooevents-custom-attendee-fields\/\" target=\"_blank\" rel=\"noopener\">FooEvents Plugin de campos personalizados de participantes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/woocommerce.com\/products\/product-add-ons\/?aff=8264&amp;cid=702463\" target=\"_blank\" rel=\"noopener\">WooCommerce Complementos de produtos<\/a> (plugin de terceiros)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Configura\u00e7\u00e3o<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Defini\u00e7\u00f5es de produtos standard<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ir para&nbsp;<strong>Produtos<\/strong>&nbsp;&gt;&nbsp;<strong>Adicionar produto<\/strong> no menu principal e preencha os campos padr\u00e3o do produto, como o t\u00edtulo, o corpo, a descri\u00e7\u00e3o, as etiquetas, as categorias, a imagem em destaque e a galeria, conforme necess\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ir para o <strong>Dados do produto<\/strong> &gt; <strong>Geral<\/strong> e definir o pre\u00e7o da reserva do local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ir para o <strong>Dados do produto<\/strong> &gt; <strong>Invent\u00e1rio<\/strong> e assegurar <strong>Gerir o stock?<\/strong> \u00e9 <em>N\u00c3O ativado<\/em>. O stock\/invent\u00e1rio ser\u00e1 definido a n\u00edvel da reserva.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Defini\u00e7\u00f5es de eventos<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ir para&nbsp;<strong>Dados do produto<\/strong>&nbsp;&gt;<strong>&nbsp;Defini\u00e7\u00f5es de eventos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ativar a funcionalidade do evento, defina o par\u00e2metro '<strong>Este produto \u00e9 um evento?<\/strong>' para \"Sim\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Definir a op\u00e7\u00e3o Tipo de evento para '<strong>Reserv\u00e1vel<\/strong>' e preencha os campos de eventos padr\u00e3o conforme necess\u00e1rio.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"584\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2020\/11\/Screen-Shot-2020-11-05-at-11.32.11-AM.png\" alt=\"\" class=\"wp-image-131987\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2020\/11\/Screen-Shot-2020-11-05-at-11.32.11-AM.png 736w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2020\/11\/Screen-Shot-2020-11-05-at-11.32.11-AM-300x238.png 300w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As defini\u00e7\u00f5es seguintes podem ser alteradas conforme necess\u00e1rio, mas para efeitos desta demonstra\u00e7\u00e3o, definimo-las da seguinte forma:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Capturar o nome completo e o endere\u00e7o de correio eletr\u00f3nico do participante? - <span style=\"color: #99cc00;\">Ativado<\/span><\/li>\n\n\n\n<li>Capturar o n\u00famero de telefone do participante? - <span style=\"color: #99cc00;\">Ativado<\/span><\/li>\n\n\n\n<li>Ordem de sele\u00e7\u00e3o das reservas - <strong>Date > Slot<\/strong><\/li>\n\n\n\n<li>Mostrar faixas hor\u00e1rias e datas de reserva - <strong>P\u00e1gina do produto<\/strong><\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Defini\u00e7\u00f5es dos bilhetes<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ir para&nbsp;<strong>Dados do produto<\/strong>&nbsp;&gt;<strong>&nbsp;Defini\u00e7\u00f5es dos bilhetes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O bilhete que o comprador receber\u00e1 ao efetuar a reserva servir\u00e1 de confirma\u00e7\u00e3o de que o local foi reservado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pode alterar o assunto do e-mail do bilhete para algo como \"Confirma\u00e7\u00e3o de reserva do local da festa\" utilizando a op\u00e7\u00e3o <strong>Assunto do e-mail do bilhete<\/strong>&nbsp;dom\u00ednio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">dom\u00ednio.\r\n\r\nPersonalize o design do bilhete conforme necess\u00e1rio e certifique-se de que ativa as seguintes defini\u00e7\u00f5es do bilhete:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Mostrar os dados do comprador ou do participante no bilhete?<\/li>\n\n\n\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Exibir detalhes personalizados do participante no bilhete?<\/li>\n\n\n\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Mostrar a op\u00e7\u00e3o \"Adicionar ao calend\u00e1rio\" no bilhete?<\/li>\n\n\n\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Anexar o ficheiro ICS do calend\u00e1rio ao e-mail do bilhete?<\/li>\n\n\n\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Exibir data e hora no bilhete?<\/li>\n\n\n\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Mostrar o c\u00f3digo de barras no bilhete?<\/li>\n\n\n\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Exibir o pre\u00e7o no bilhete?<\/li>\n\n\n\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Mostrar os detalhes da reserva no bilhete?<\/li>\n\n\n\n<li><span style=\"color: #ff0000;\">Desativado<\/span>\u00a0- Enviar o bilhete por correio eletr\u00f3nico ao participante em vez de ao comprador?<\/li>\n\n\n\n<li><span style=\"color: #99cc00;\">Ativado<\/span> - Bilhetes por correio eletr\u00f3nico?<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Campos personalizados de participantes<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ir para&nbsp;<strong>Dados do produto<\/strong>&nbsp;&gt;<strong> Campos personalizados de participantes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui pode criar campos personalizados para registar os requisitos alimentares do comprador, a sele\u00e7\u00e3o do tema da festa e quaisquer informa\u00e7\u00f5es de consentimento ou indemniza\u00e7\u00e3o necess\u00e1rias. Estes campos ser\u00e3o apresentados na p\u00e1gina de pagamento e s\u00e3o facultativos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"277\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.39.04.png\" alt=\"\" class=\"wp-image-133391\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.39.04.png 822w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.39.04-300x101.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.39.04-768x259.png 768w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Defini\u00e7\u00f5es de reservas<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ir para&nbsp;<strong>Dados do produto<\/strong>&nbsp;&gt;<strong> Defini\u00e7\u00f5es de reservas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Crie uma faixa hor\u00e1ria chamada \"Manh\u00e3\", defina a hora (09:00 a.m.) e adicione todas as datas em que a faixa hor\u00e1ria est\u00e1 dispon\u00edvel (06 de maio de 2022 - 14 de maio de 2022). Uma vez que o local s\u00f3 pode ser reservado uma vez por faixa hor\u00e1ria, pode definir o valor do stock para cada data como \"1\" para evitar reservas em excesso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois de concluir estes passos, utilize o \u00edcone duplicar junto ao \u00edcone do lixo para copiar a ranhura. Pode ent\u00e3o mudar o nome da segunda ranhura para \"Tarde\", alterar a hora e modificar as datas, se necess\u00e1rio.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1405\" height=\"780\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.44.23.png\" alt=\"\" class=\"wp-image-133393\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.44.23.png 1405w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.44.23-300x167.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.44.23-1024x568.png 1024w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.44.23-768x426.png 768w\" sizes=\"auto, (max-width: 1405px) 100vw, 1405px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Terminologia de eventos<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ir para&nbsp;<strong>Dados do produto<\/strong>&nbsp;&gt;<strong> Terminologia de eventos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesta sec\u00e7\u00e3o, pode alterar os termos utilizados para descrever o seu evento. Estes termos ser\u00e3o apresentados em todo o s\u00edtio, bem como no bilhete.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"350\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.28.45.png\" alt=\"\" class=\"wp-image-133390\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.28.45.png 970w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.28.45-300x108.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.28.45-768x277.png 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Complementos<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Pode oferecer complementos adicionais, como pacotes de festas, servi\u00e7os de entretenimento ou aluguer de equipamento adicional, utilizando o <a href=\"https:\/\/woocommerce.com\/products\/product-add-ons\/?aff=8264&amp;cid=702463\" target=\"_blank\" rel=\"noopener\">WooCommerce Complementos de produtos<\/a> extens\u00e3o. Esta \u00e9 uma extens\u00e3o de terceiros desenvolvida pelo WooCommerce e pode ser adquirida no WooCommerce Marketplace.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma vez instalado, pode ir a <strong>Dados do produto<\/strong>&nbsp;&gt;<strong> Complementos<\/strong> e criar add-ons de produtos personalizados, conforme necess\u00e1rio. Para obter informa\u00e7\u00f5es detalhadas sobre como configurar estes campos, consulte a sec\u00e7\u00e3o <a href=\"https:\/\/woocommerce.com\/document\/product-add-ons\/\" target=\"_blank\" rel=\"noopener\">Documenta\u00e7\u00e3o de complementos do produto WooCommerce<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1082\" height=\"776\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.53.10.png\" alt=\"\" class=\"wp-image-133394\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.53.10.png 1082w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.53.10-300x215.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.53.10-1024x734.png 1024w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.53.10-768x551.png 768w\" sizes=\"auto, (max-width: 1082px) 100vw, 1082px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pode agora&nbsp;<strong>Guardar&nbsp;<\/strong>e<strong>&nbsp;Publicar<\/strong> o seu produto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Utiliza\u00e7\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os clientes podem selecionar a data e a faixa hor\u00e1ria da reserva do local na p\u00e1gina do produto do seu s\u00edtio Web. Podem tamb\u00e9m selecionar complementos adicionais antes de procederem ao checkout.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1207\" height=\"625\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.56.39.png\" alt=\"\" class=\"wp-image-133395\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.56.39.png 1207w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.56.39-300x155.png 300w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.56.39-1024x530.png 1024w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.56.39-768x398.png 768w\" sizes=\"auto, (max-width: 1207px) 100vw, 1207px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No momento do checkout, os clientes podem ser solicitados a introduzir quaisquer informa\u00e7\u00f5es adicionais utilizando os campos personalizados de participantes.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"672\" height=\"782\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.59.19.png\" alt=\"\" class=\"wp-image-133396\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.59.19.png 672w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-13-at-13.59.19-258x300.png 258w\" sizes=\"auto, (max-width: 672px) 100vw, 672px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma vez conclu\u00edda a encomenda, o cliente receber\u00e1 uma mensagem de correio eletr\u00f3nico de confirma\u00e7\u00e3o com todas as informa\u00e7\u00f5es relevantes para a reserva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Check-ins de participantes utilizando as aplica\u00e7\u00f5es FooEvents<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pode gerir as reservas utilizando a aplica\u00e7\u00e3o gratuita <a href=\"https:\/\/www.fooevents.com\/features\/apps\/\" target=\"_blank\" rel=\"noopener\">FooEvents Aplica\u00e7\u00e3o de check-ins<\/a>. Os eventos reserv\u00e1veis funcionam de forma diferente dos outros eventos quando visualizados na aplica\u00e7\u00e3o e utilizam ecr\u00e3s personalizados que facilitam a gest\u00e3o das reservas. Os c\u00f3digos de barras dos bilhetes tamb\u00e9m podem ser lidos na aplica\u00e7\u00e3o para acelerar o processo de check-in.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"713\" height=\"690\" src=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/app-party-venue.png\" alt=\"\" class=\"wp-image-133397\" title=\"\" srcset=\"https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/app-party-venue.png 713w, https:\/\/help.fooevents.com\/wp-content\/uploads\/2022\/07\/app-party-venue-300x290.png 300w\" sizes=\"auto, (max-width: 713px) 100vw, 713px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Perguntas e coment\u00e1rios<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tem uma pergunta antes de comprar? Por favor&nbsp;<a href=\"https:\/\/www.fooevents.com\/contact-us\/\" target=\"_blank\" rel=\"noopener\">entrar em contacto<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 comprou e precisa de assist\u00eancia?&nbsp;<a href=\"https:\/\/www.fooevents.com\/support\/\" target=\"_blank\" rel=\"noopener\">Contactar a nossa equipa de apoio<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Scenario A party venue company would like to allow customers to make venue bookings through their website. The venue can be booked on specific days at two different time slots. The company also offers additional services such as party packs, entertainment, and equipment hire that are offered as upsells. When an customer purchases a ticket, [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":2357,"menu_order":7,"template":"","doc_tag":[470,379,376,4,375,318,319,366,104,317,469,76],"class_list":["post-133388","docs","type-docs","status-publish","hentry","doc_tag-add-ons","doc_tag-bookable-product","doc_tag-booking","doc_tag-email","doc_tag-fooevents-bookings","doc_tag-fooevents-for-woocommerce","doc_tag-fooevents-multi-day","doc_tag-howto","doc_tag-settings","doc_tag-use-case","doc_tag-venue","doc_tag-woocommerce"],"_links":{"self":[{"href":"https:\/\/help.fooevents.com\/pt\/wp-json\/wp\/v2\/docs\/133388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.fooevents.com\/pt\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/help.fooevents.com\/pt\/wp-json\/wp\/v2\/types\/docs"}],"version-history":[{"count":1,"href":"https:\/\/help.fooevents.com\/pt\/wp-json\/wp\/v2\/docs\/133388\/revisions"}],"predecessor-version":[{"id":148657,"href":"https:\/\/help.fooevents.com\/pt\/wp-json\/wp\/v2\/docs\/133388\/revisions\/148657"}],"up":[{"embeddable":true,"href":"https:\/\/help.fooevents.com\/pt\/wp-json\/wp\/v2\/docs\/2357"}],"wp:attachment":[{"href":"https:\/\/help.fooevents.com\/pt\/wp-json\/wp\/v2\/media?parent=133388"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/help.fooevents.com\/pt\/wp-json\/wp\/v2\/doc_tag?post=133388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}